{"id":778,"date":"2018-03-24T15:34:48","date_gmt":"2018-03-24T14:34:48","guid":{"rendered":"https:\/\/urdla.com\/blog\/?p=778"},"modified":"2020-04-14T19:37:30","modified_gmt":"2020-04-14T17:37:30","slug":"anne-valerie-gasc-a","status":"publish","type":"post","link":"https:\/\/urdla.com\/blog\/anne-valerie-gasc-a\/","title":{"rendered":"A, Anne-Val\u00e9rie Gasc"},"content":{"rendered":"<h6 class=\"p1\" style=\"text-align: right;\"><\/h6>\n<p><img loading=\"lazy\" class=\"alignleft size-full wp-image-786\" src=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-31.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-31.jpg 1500w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-31-300x200.jpg 300w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-31-768x512.jpg 768w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-31-1024x683.jpg 1024w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-31-272x182.jpg 272w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>Accueillie en r\u00e9sidence en f\u00e9vrier 2017, Anne-Val\u00e9rie Gasc r\u00e9alise, sur le principe du monotype (r\u00e9v\u00e9lation d\u2019une empreinte par contact), 26 lithographies de pierres d\u00e9class\u00e9es et choisies indiff\u00e9remment au sein de la biblioth\u00e8que de pierres de l\u2019URDLA. Vingt-six empreintes de pierres, autant que de lettres de l\u2019alphabet : le rapport au texte s\u2019impose. Chaque impression, nomm\u00e9e d\u2019une lettre, compose un livre d\u2019artiste, un \u00ab livre de tous les livres \u00bb \u00e9dit\u00e9, la m\u00eame ann\u00e9e, par Lendroit \u00c9ditions. Intitul\u00e9 <span class=\"s1\"><i>Twenty-six Blank Rocks<\/i><\/span>, le \u00ab blank \u00bb du titre renvoie, en langue fran\u00e7aise, au blanc de la page vierge. En langue anglaise, il induit quelque chose plus proche de la table rase, de la remise \u00e0 z\u00e9ro.<\/p>\n<p><img loading=\"lazy\" class=\"alignleft size-full wp-image-782\" src=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-5.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-5.jpg 1500w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-5-300x200.jpg 300w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-5-768x512.jpg 768w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-5-1024x683.jpg 1024w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-5-272x182.jpg 272w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/p>\n<p class=\"p2\">Ce livre cl\u00f4t la trilogie r\u00e9volutionnaire de l\u2019artiste, en dialogue avec les trois premiers livres d\u2019artiste d\u2019Ed Ruscha. Pour Anne-Val\u00e9rie Gasc, <span class=\"s1\"><i>Twenty-six Gasoline Stations <\/i><\/span>(1963) \u00ab localise des points de ressource en liquide inflammable \u00bb ; <span class=\"s1\"><i>Various Small Fires and Milk <\/i><\/span>(1964) \u00ab collectionne des d\u00e9tonateurs incendiaires \u00bb et <span class=\"s1\"><i>Some Los Angeles Apartments <\/i><\/span>(1965), \u00ab paru l\u2019ann\u00e9e des \u00e9meutes de banlieues \u00e0 Los Angeles, fait l\u2019\u00e9tat des lieux silencieux et statique, comme suspendu dans le temps juste avant la r\u00e9volte, des cibles architecturales qui vont br\u00fbler \u00bb. La lecture qu\u2019Anne-Val\u00e9rie Gasc fait de ces livres, a inaugur\u00e9 un jeu de citations : en 2008, na\u00eet <span class=\"s1\"><i>Some Belsunce Apartments<\/i><\/span>, promenade photographique architecturale dans le quartier de Belsunce dont la chronologie des d\u00e9molitions fait appara\u00eetre la strat\u00e9gie politique de gentrification de ce centre-ville ancien. En 2014, les \u00c9ditions Florence Loewy publient <span class=\"s1\"><i>Various Small Sparks<\/i><\/span>, flip book construit au rythme des tirs explosifs du foudroyage int\u00e9gral, 20 ans auparavant, des dix tours D\u00e9mocratie du quartier des Minguettes \u00e0 V\u00e9nissieux. <span class=\"s1\"><i>Twenty-six Blank Rocks<\/i><\/span>, son dernier opus ici pr\u00e9sent\u00e9, substitue \u00e0 l\u2019essence de Ruscha, l\u2019encre lithographique, noire et grasse comme du p\u00e9trole. Il appelle la citation de St\u00e9phane Mallarm\u00e9, au lendemain de l\u2019attentat anarchiste du Palais Bourbon : \u00ab Je ne sais pas d\u2019autre bombe, qu\u2019un livre. \u00bb<\/p>\n<p><img loading=\"lazy\" class=\"alignleft size-full wp-image-783\" src=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-11.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-11.jpg 1500w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-11-300x200.jpg 300w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-11-768x512.jpg 768w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-11-1024x683.jpg 1024w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-11-272x182.jpg 272w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/p>\n<p class=\"p2\">L\u2019exposition \u00ab A \u00bb d\u2019Anne-Val\u00e9rie Gasc est compos\u00e9e de 26 empreintes lithographiques, de 5 pierres lithographiques d\u00e9class\u00e9es encr\u00e9es de noir, et du livre <span class=\"s1\"><i>Twenty-six Blank Rocks<\/i><\/span>. La contradiction entre poids et suspension, massivit\u00e9 et apesanteur, sera la r\u00e8gle du jeu de l\u2019accrochage des oeuvres. C\u2019est \u00e0 la rencontre de cette tension entre la fragilit\u00e9 du papier, son pouvoir de diss\u00e9mination, et la puissance d\u2019un combat pour la libert\u00e9, que nous invitons les visiteurs.<\/p>\n<p><a href=\"http:\/\/pointcontemporain.com\/anne-valerie-gasc-entretien\/\"><strong>Lire l\u2019entretien dans Point Contemporain &gt;&gt;<\/strong><\/a><\/p>\n<p><img loading=\"lazy\" class=\"alignleft size-full wp-image-784\" src=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-1.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-1.jpg 1500w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-1-300x200.jpg 300w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-1-768x512.jpg 768w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-1-1024x683.jpg 1024w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2019\/09\/BD-URDLA-Gasc-1-272x182.jpg 272w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Je voudrais que mes livres soient des sortes de bistouris,<br \/>\nde cocktails Molotov ou de galeries de mine,<br \/>\net qu\u2019ils se carbonisent apr\u00e8s usage \u00e0\u00a0 la mani\u00e8re des feux d\u2019artifice. \u00bb<br \/>\nMichel Foucault, \u00c2\u00ab Sur la sellette \u00c2\u00bb (entretien avec J.-L. Ezine), 1975.<\/p>\n","protected":false},"author":4,"featured_media":785,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/778"}],"collection":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/comments?post=778"}],"version-history":[{"count":10,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/778\/revisions"}],"predecessor-version":[{"id":1792,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/778\/revisions\/1792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/media\/785"}],"wp:attachment":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/media?parent=778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/categories?post=778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/tags?post=778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}