{"id":4484,"date":"2020-10-26T07:18:27","date_gmt":"2020-10-26T06:18:27","guid":{"rendered":"https:\/\/urdla.com\/blog\/?p=4484"},"modified":"2021-01-07T17:34:03","modified_gmt":"2021-01-07T16:34:03","slug":"got-a-match-blandine-devers","status":"publish","type":"post","link":"https:\/\/urdla.com\/blog\/got-a-match-blandine-devers\/","title":{"rendered":"<i>Got a match\u00a0?<\/i>, <\/br>Blandine Devers"},"content":{"rendered":"<p class=\"p1\" style=\"text-align: right;\"><i>Lise il faut attiser le po\u00eale qui s\u2019\u00e9teint<br \/>\n<\/i>Guillaume Apollinaire, \u00ab\u00a0Les Femmes\u00a0\u00bb in <i>Alcools<\/i><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p4\">Sur la bo\u00eete qu\u2019elle tend, \u00e0 son prochain en qu\u00eate de lumi\u00e8re, ses initiales, M. M.<\/p>\n<p class=\"p4\">Dans la nuit froide, la nuit danoise, la nuit de mille huit cents, une petite fille \u00e9puise ses derni\u00e8res allumettes. Chacune convoque un sc\u00e9nario \u2013 chaleur, banquets, sa grand-m\u00e8re retrouv\u00e9e. Elle invente le cin\u00e9ma. Le rideau tombe. Tout n\u2019\u00e9tait que projection. Les t\u00e9n\u00e8bres ont gagn\u00e9.<\/p>\n<p class=\"p4\">\u00c0 URDLA, Ma\u00eft\u00e9 Marra joue avec le feu. Dans la nuit de presque hiver, des passants s\u2019enfonceront dans les m\u00e9andres des archives. La lumi\u00e8re du scanner, rejou\u00e9e par les \u00e9crans, effleurera l\u2019instant. La lumi\u00e8re froide de l\u2019ali\u00e9nation administrative, des plus douloureux diagnostics, rejoint la flamme ardente.<\/p>\n<p class=\"p4\">Ma\u00eft\u00e9 Marra imagine que le r\u00e9alisateur de <i>North by Northwest<\/i>, Alfred Hitchcock, est aussi le spectateur de <i>Only Angels Have Wings<\/i> et que les deux films se font \u00e9cho. Entre trag\u00e9die et com\u00e9die, le motif de l\u2019allumette ponctue le deuxi\u00e8me cit\u00e9. Cary Grant, qui y joue Geoffrey Carter, pilote, n\u2019en poss\u00e8de pas, il doit sans cesse qu\u00e9mander l\u2019objet. \u00c0 l\u2019origine du feu sacr\u00e9\u00a0:<br \/>\nCARTER. \u2013 Got a match ?<br \/>\nBONNIE.\u2013 Don\u2019t you ever have any\u00a0?<br \/>\nCARTER.\u2013 Don\u2019t believe in laying in a supply of anything.<br \/>\nBONNIE.\u2013 Matches, marbles, money or women\u00a0?<br \/>\nCARTER.\u2013 That\u2019s right.<br \/>\nBONNIE.\u2013 No looking ahead \u2013 no tomorrows \u2013 juste today\u00a0?<br \/>\nCARTER.\u2013 That\u2019s right.<\/p>\n<p class=\"p4\">Mal engag\u00e9, malentendu, m\u00e9prise, \u00e9puisement. Le cran d\u2019arr\u00eat \u00e0 l\u2019exacte mesure exponentielle. Faire feu de tout bois.<\/p>\n<p class=\"p4\">DURGENCE LAMOUR est un cri silencieux. Everywhere. Nulle part. La grande illusion. Invitation. Arnaque\u00a0! Sous-tend. Se d\u00e9robe. Se tait. Se joue. Pudique. Hurl\u00e9. Absent. Polymorphe. \u00c9puis\u00e9. Renouvel\u00e9. Feint. Multiple. \u00c9chappe. Enserre. D\u00e9borde. Se heurte. Insaisissable. Incontr\u00f4lable. Surgit. Resurgit. Luminescent. Se camoufle. Travesti. N\u2019en finit point de mourir, n\u2019en finit pas de rena\u00eetre. In\u00e9puisable boucle. Qu\u00eate de vitalit\u00e9. Sentiment polichinelle.<\/p>\n<p class=\"p4\">Tenir hors de port\u00e9e des enfants.<\/p>\n<p class=\"p4\">Dites moi \u00e0 quel feu \u00e0 vous vous br\u00fblez, je vous dirai qui vous \u00eates.<\/p>\n<p><img loading=\"lazy\" class=\"alignleft size-full wp-image-4488\" src=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/10\/match.png\" alt=\"\" width=\"1394\" height=\"789\" srcset=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/10\/match.png 1394w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/10\/match-300x170.png 300w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/10\/match-1024x580.png 1024w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/10\/match-768x435.png 768w\" sizes=\"(max-width: 1394px) 100vw, 1394px\" \/><\/p>\n<p class=\"p4\">M\u00e9fiez-vous des clich\u00e9s, des arch\u00e9types. De la plasticit\u00e9 de Cary Grant. Sachez d\u00e9celer le trouble dans la s\u00fbret\u00e9 la plus assur\u00e9e. Des initiales peuvent \u00eatre matrices. Ma\u00eft\u00e9 Marra craque ses allumettes \u00e0 la surface du cuivre, de l\u2019encre, de la feuille\u2026 mouill\u00e9e. Pour que <i>\u00e7a matche<\/i>, le taille-doucier sait qu\u2019il faut que le papier soit amoureux. D\u2019un baiser l\u2019\u00e9prouver. Ma\u00eft\u00e9 Marra s\u2019empare de la technique de l\u2019estampe la plus manuelle, la plus tactile.<\/p>\n<p class=\"p4\">Un souffle s\u2019\u00e9crit, dit l\u2019autre. Relie des feuillets mobiles. \u00c0 caresser.<\/p>\n<p class=\"p4\">Il n\u2019y aura de film que si vous acceptez de vous pr\u00eater au montage. De devenir personnage. Tenter de faire figure. Vivre, un peu plus loin, de fiction en fiction.<\/p>\n<p class=\"p5\">CARTER.\u2013 Oh\u2026 got a match\u00a0?<br \/>\nBONNIE.\u2013 Say, don\u2019t you think it\u2019s about time you started carrying some\u00a0?<\/p>\n<p class=\"p4\">C\u2019est <i>elle<\/i>. Qui souffle la flamme de l\u2019allumette. C\u2019est <i>elle<\/i> encore qui menace Cary \u00e0 bout portant. Retournement de clich\u00e9s genr\u00e9s. Nulle partie n\u2019est jou\u00e9e d\u2019avance. Il y aura toujours la possibilit\u00e9 de gratter. Et, dans une expiration, \u00e9teindre ou \u00e9treindre.<\/p>\n<p><img loading=\"lazy\" class=\"alignleft size-full wp-image-4498\" src=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/10\/Capture-de\u0301cran-2020-10-12-a\u0300-08.18.52.png\" alt=\"\" width=\"981\" height=\"703\" srcset=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/10\/Capture-de\u0301cran-2020-10-12-a\u0300-08.18.52.png 981w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/10\/Capture-de\u0301cran-2020-10-12-a\u0300-08.18.52-300x215.png 300w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/10\/Capture-de\u0301cran-2020-10-12-a\u0300-08.18.52-768x550.png 768w\" sizes=\"(max-width: 981px) 100vw, 981px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sur la bo\u00eete qu\u2019elle tend, \u00e0 son prochain en qu\u00eate de lumi\u00e8re, ses initiales, M. M.<\/p>\n","protected":false},"author":4,"featured_media":4485,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[12],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/4484"}],"collection":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/comments?post=4484"}],"version-history":[{"count":11,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/4484\/revisions"}],"predecessor-version":[{"id":4704,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/4484\/revisions\/4704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/media\/4485"}],"wp:attachment":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/media?parent=4484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/categories?post=4484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/tags?post=4484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}