{"id":4046,"date":"2020-06-22T18:00:32","date_gmt":"2020-06-22T16:00:32","guid":{"rendered":"https:\/\/urdla.com\/blog\/?p=4046"},"modified":"2020-09-03T14:12:55","modified_gmt":"2020-09-03T12:12:55","slug":"daniel-aulagnier-1943-2020","status":"publish","type":"post","link":"https:\/\/urdla.com\/blog\/daniel-aulagnier-1943-2020\/","title":{"rendered":"Daniel Aulagnier, 1943-2020"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">Daniel Aulagnier est mort ce mardi 16 juin 2020 au matin. Son \u0153uvre prot\u00e9iforme d\u00e9bute dans les ann\u00e9es 70 par des performances qui engagent le corps de l\u2019artiste. Peu \u00e0 peu la pr\u00e9sence r\u00e9elle du corps glisse par m\u00e9taphore dans les dessins et les volumes. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Sa rencontre avec les presses d\u2019URDLA en 2006 permet l\u2019impression et l\u2019\u00e9dition de trois grand lithographies, <a href=\"https:\/\/urdla.com\/catalogue\/190-assemblage-i.html\" target=\"_blank\" rel=\"noopener noreferrer\">\u00ab\u00a0Assemblages.\u00a0\u00bb<\/a> Des outils imaginaires, sortis de l\u2019industrie qui a pr\u00e9sid\u00e9 \u00e0 l\u2019invention de nos presses s\u2019agitent sur l\u2019espace de la feuille. Sont-ce des outils ou bien des signes, des lettres en devenir ?<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">En 2008, sa tr\u00e8s grande linogravure <a href=\"https:\/\/urdla.com\/catalogue\/195-des-signes-pour-le-dire.html\" target=\"_blank\" rel=\"noopener noreferrer\">\u00ab\u00a0Des signes pour le dire\u00a0\u00bb<\/a> ouvrait l\u2019exposition de nos trente ans, elle a depuis aussi ouvert l\u2019hommage que nous rendait la Biblioth\u00e8que nationale de France en 2016. \u00c0 l\u2019\u00e9clatement des outils vient se m\u00ealer la lettre que depuis quelques ann\u00e9es il manipule, accroche et colle au corps des visiteurs qui participent aux nombreuses performances qu\u2019il a organis\u00e9es. C\u2019est le corps qui articule la lettre et lui donne sa forme. <a href=\"https:\/\/urdla.com\/blog\/la-lettre-est-loutil-du-motdaniel-aulagnier\/\" target=\"_blank\" rel=\"noopener noreferrer\"><em>La lettre est l\u2019outil du corps<\/em><\/a> nous \u00e9crivait-il dans la Courte \u00e9chelle en avril dernier ; la lettre fa\u00e7onne le corps lui r\u00e9pondrais-je. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Son travail a \u00e9t\u00e9 pr\u00e9sent\u00e9 dans de nombreux centre d\u2019arts et mus\u00e9es en France, en Europe et au-del\u00e0. \u00c0 Lyon, le public a pu mesurer l\u2019ampleur de son \u0153uvre dans l\u2019exposition \u00e0 quatre mains \u00e0 URDLA, en 2014 <a href=\"https:\/\/urdla.com\/blog\/assemblages-daniel-aulagnier-frederic-cordier\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00ab Assemblages. \u00bb<\/a> Ces pi\u00e8ces ont toujours manifester ce d\u00e9sir de la rencontre. Aussi l\u2019exposition \u00e9tait elle-m\u00eame l\u2019assemblage de Daniel Aulagnier et de Fr\u00e9d\u00e9ric Cordier, de quarante deux ans son cadet. Il r\u00e9pondait \u00e0 la rigueur rectiligne des linogravures de Cordier par l\u2019\u00e9clatement des formes et des \u0153uvres-m\u00eame produites pour l\u2019occasion \u00e0 URDLA. Ces \u00ab\u00a0<a href=\"https:\/\/urdla.com\/catalogue\/1927-eclaboussures-i.html\" target=\"_blank\" rel=\"noopener noreferrer\">\u00c9claboussures\u00a0<\/a>\u00bb sont uniques dans le vaste catalogue URDLA. La m\u00eame ann\u00e9e la galerie Anne-Marie et Roland Pallade lui consacrait une exposition \u00e0 Lyon.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u00c0 la toute fin de l\u2019ann\u00e9e derni\u00e8re nous entamions une nouvelle s\u00e9rie de lithographies. Le titre, <a href=\"https:\/\/urdla.com\/accueil\/2430-le-corps-la-rue-la-ville-1.html\" target=\"_blank\" rel=\"noopener noreferrer\">\u00ab\u00a0 Le corps, la rue, la ville \u00bb<\/a>, indique la mani\u00e8re dont il noue, dont il nouait \u00e0 la fin de son \u0153uvre, les \u00e9l\u00e9ments qu\u2019il n\u2019a eu de cesse d\u2019interroger. Nous avons pu r\u00e9aliser la premi\u00e8re \u00e9tape : la ville, c\u2019est Villeurbanne. La seconde restera en suspend, il s\u2019agissait de Paris pour une exposition pr\u00e9vue \u00e0 l\u2019automne de sa galerie parisienne, Marguerite Milin. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Depuis 2006, il est un compagnon proche d\u2019URDLA, membre de l\u2019association, hier il adressait son pouvoir pour l\u2019Assembl\u00e9e g\u00e9n\u00e9rale de juillet, estimant qu\u2019il ne viendra pas \u00e0 Villeurbanne. Pourtant, r\u00e9it\u00e9rant son soutien ind\u00e9fectible, nous r\u00e9alisions un nouveau multiple, variation du badge URDLA \u00e9moi. URDLA et moi y sera d\u00e9voil\u00e9. Christine Vaisse, Pr\u00e9sidente d\u2019URDLA, le Conseil d\u2019administration, les salari\u00e9s d\u2019URDLA et moi-m\u00eame adressons nos plus vives pens\u00e9es \u00e0 Jos\u00e9e, sa femme, l\u2019un et l\u2019autre semblaient ins\u00e9parable, et \u00e0 sa famille. Nous avons aujourd\u2019hui perdu un ami.<\/span><\/p>\n<p><img loading=\"lazy\" class=\"wp-image-4071 size-large alignnone\" src=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/06\/MG_0815-683x1024.jpg\" alt=\"\" width=\"683\" height=\"1024\" srcset=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/06\/MG_0815-683x1024.jpg 683w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/06\/MG_0815-200x300.jpg 200w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/06\/MG_0815-768x1152.jpg 768w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/06\/MG_0815-1024x1536.jpg 1024w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/06\/MG_0815-1365x2048.jpg 1365w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/06\/MG_0815-1333x2000.jpg 1333w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/06\/MG_0815-1568x2352.jpg 1568w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2020\/06\/MG_0815-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Daniel Aulagnier est mort ce mardi 16 juin 2020 au matin. Son \u0153uvre prot\u00e9iforme d\u00e9bute dans les ann\u00e9es 70\u2026<\/p>\n","protected":false},"author":4,"featured_media":2499,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/4046"}],"collection":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/comments?post=4046"}],"version-history":[{"count":14,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/4046\/revisions"}],"predecessor-version":[{"id":4073,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/4046\/revisions\/4073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/media\/2499"}],"wp:attachment":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/media?parent=4046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/categories?post=4046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/tags?post=4046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}