{"id":25974,"date":"2024-05-24T12:18:35","date_gmt":"2024-05-24T10:18:35","guid":{"rendered":"https:\/\/urdla.com\/blog\/?p=25974"},"modified":"2024-10-29T11:21:19","modified_gmt":"2024-10-29T10:21:19","slug":"damien-deroubaix-yannick-vey-le-soleil-poudroie-et-lherbe-verdoie-cyrille-noirjean","status":"publish","type":"post","link":"https:\/\/urdla.com\/blog\/damien-deroubaix-yannick-vey-le-soleil-poudroie-et-lherbe-verdoie-cyrille-noirjean\/","title":{"rendered":"<i> Le soleil poudroie et l&rsquo;herbe verdoie, <\/i><\/br> Cyrille Noirjean"},"content":{"rendered":"<p class=\"p1\">C\u2019\u00e9tait il y a quinze ans ; les <i>Cavaliers de l\u2019Apocalpyse<\/i> entra\u00eenaient URDLA r\u00e9nov\u00e9e et restaur\u00e9e vers une nouvelle d\u00e9cennie. <a href=\"https:\/\/urdla.com\/artiste\/93-deroubaix\">Damien Deroubaix<\/a> avait d\u00e9j\u00e0 fa\u00e7onn\u00e9 et nou\u00e9 le tr\u00e9pied \u00e9labor\u00e9 lors de ses ann\u00e9es de formation \u00e0 Saint-\u00c9tienne, qui lui sert aujourd\u2019hui encore d\u2019appui : la culture picturale classique, les violences du monde, le <i>Heavy Metal<\/i>. Tr\u00e8s t\u00f4t aux beaux-arts rencontre-t-il la gravure (entendons ici l\u2019image imprim\u00e9e dans la multiplicit\u00e9 de ses techniques). Les premi\u00e8res gravures \u00e9dit\u00e9es \u00e0 URDLA (2001) \u2013 qu\u2019il dit ne plus pouvoir regarder \u2013 sont les t\u00e9moins du temps o\u00f9 le langage plastique commence de s\u2019articuler. <a href=\"https:\/\/urdla.com\/blog\/apokalyptische-reiter\/\" target=\"_blank\" rel=\"noopener\"><i>Apokalyptische Reiter<\/i><\/a> (octobre-d\u00e9cembre 2009) manifeste son go\u00fbt allemand, son regard ac\u00e9r\u00e9 pour les classiques et un usage singulier de la citation et de la reprise picturale. Il s\u2019agissait l\u00e0 d\u2019Albrecht D\u00fcrer : dans cette s\u00e9rie de tr\u00e8s grandes gravures sur bois, les cr\u00e9atures polymorphes associaient des \u00e9l\u00e9ments graphiques tout \u00e0 fait identifiables : aile de la <a href=\"https:\/\/urdla.com\/catalogue\/343-dass-grosse-gluck.html\" target=\"_blank\" rel=\"noopener\">Grande N\u00e9m\u00e9sis<\/a>, <a href=\"https:\/\/urdla.com\/catalogue\/353-sans-titre.html\" target=\"_blank\" rel=\"noopener\">t\u00eate de bouc<\/a>, <i>totenkopf<\/i> \u00e0 la mani\u00e8re d\u2019un cabinet de curiosit\u00e9s des actualit\u00e9s.<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-25984 aligncenter\" src=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-villeurbanne-26-scaled.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-villeurbanne-26-scaled.jpg 2560w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-villeurbanne-26-300x200.jpg 300w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-villeurbanne-26-1024x683.jpg 1024w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-villeurbanne-26-768x512.jpg 768w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-villeurbanne-26-1536x1024.jpg 1536w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-villeurbanne-26-2048x1365.jpg 2048w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-villeurbanne-26-2000x1333.jpg 2000w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-villeurbanne-26-1568x1045.jpg 1568w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-villeurbanne-26-272x182.jpg 272w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p class=\"p1\">\u00c0 peu pr\u00e8s au m\u00eame moment apparaissaient dans les expositions personnelles de Deroubaix des <i>Family Tree<\/i> : de grands dessins muraux, dont les fleurs ou les fruits \u00e9taient les \u0153uvres d\u2019autres artistes. Dans ces g\u00e9n\u00e9alogies subjectives l\u2019artiste m\u00e9nageait une place aux autres et offrait au visiteur la possibilit\u00e9 de lire des amiti\u00e9s, des influences, des connivences. La courtoise est rare. Parmi les <i>Family Jewels<\/i> : Yannick Vey, un conscrit des Beaux-Arts st\u00e9phanois. Il est sculpteur : le bois, le marbre, l\u2019acier. L\u2019habilet\u00e9 acquise dans la ciselure ouvre la voie \u00e0 de grandes dentelles d\u2019aquarelle. Dans le va-et-vient de la force, de l\u2019engagement physique et du bruit constitutif du m\u00e9tier de sculpteur vers le calme, la contemplation et le silence du dessin c\u2019est aux violences de la psych\u00e9<span class=\"Apple-converted-space\">\u00a0 <\/span>qu\u2019il s\u2019attache.<\/p>\n<p class=\"p1\"><i>Polymorphie<\/i> est d\u00e8s lors d\u2019\u00e9vidence ; elle se feuillette dans la pratique (les media), dans les images (c\u2019est la mani\u00e8re m\u00eame de toute repr\u00e9sentation) et dans l\u2019amiti\u00e9 (elle en est le fondement). Le n\u0153ud insoluble sur lequel abouti Sigmund Freud d\u2019intrication de l\u2019intime et du collectif est le lieu de d\u00e9part de l\u2019un et de l\u2019autre artiste : chacun depuis sa rive. C\u2019\u00e9tait il y a quatre-vingt-quinze ans, en 1929, la question se formulait ainsi : \u00ab\u00a0Le progr\u00e8s de la civilisation saura-t-il, et dans quelle mesure, dominer les perturbations apport\u00e9es \u00e0 la vie en commun par les pulsions humaines d&rsquo;agression et d&rsquo;autodestruction ? \u00c0 ce point de vue, l&rsquo;\u00e9poque actuelle m\u00e9rite peut-\u00eatre une attention toute particuli\u00e8re. Les hommes d&rsquo;aujourd&rsquo;hui ont pouss\u00e9 si loin la ma\u00eetrise des forces de la nature qu&rsquo;avec leur aide il leur est devenu facile de s\u2019exterminer mutuellement jusqu&rsquo;au dernier. Ils le savent bien, et c&rsquo;est ce qui explique une bonne part de leur agitation pr\u00e9sente, de leur malheur et de leur angoisse. Et maintenant, il y a lieu d&rsquo;attendre que l&rsquo;autre des deux \u201c puissances c\u00e9lestes \u201d, l&rsquo;Eros \u00e9ternel, tente un effort afin de s&rsquo;affirmer dans la lutte qu&rsquo;il m\u00e8ne contre son adversaire non moins immortel.\u00a0\u00bb <i>(Malaise dans la civilisation).<\/i> Les \u0153uvres (peintures, sculptures, dessins, lithographies) que r\u00e9unit l\u2019exposition se logent dans l\u2019ouverture \u00e0 l\u2019invention et \u00e0 la cr\u00e9ation que le pessimisme intransigeant de Freud (la formule est d\u2019Adorno) offre. Le poulpe de Deroubaix ouvre l\u2019exposition : animal qui passe partout, qui se faufile, qui s\u2019\u00e9tire, capable de coordonner sa couleur \u00e0 la lumi\u00e8re et \u00e0 son environnement ; il est aussi un impossible du peintre. Comment fixer ce qui est mouvant de couleurs et de formes ? Difficile d\u2019\u00e9vacuer qu\u2019avec son nom de pieuvre l\u2019animal sert \u00e0 imager les dominations et les mafias, soit <i>les pulsions d\u2019agressions et d\u2019autodestruction collectives<\/i> : il para\u00eet que m\u00eame s\u2019il est d\u00e9capit\u00e9 les tentacules peuvent poursuivre leur office. La gamme chromatique de la peinture \u00e0 l\u2019huile s\u2019\u00e9claire des collages de gravures sur bois imprim\u00e9es sur papier japon.<span class=\"Apple-converted-space\">\u00a0 <\/span>Le voisinage de la lithographie en noir permet d\u2019apercevoir l\u2019art de Deroubaix. Tout d\u2019abord au fil des ans, les motifs emprunt\u00e9s \u00e0 l\u2019histoire de l\u2019art ou surgis d\u2019on ne sait o\u00f9, se superposent, s\u2019affirment puis disparaissent lentement. Ainsi la forme du poulpe n\u2019est pas sans \u00e9voquer les ampoules noires qui, il y a quelques ann\u00e9es peuplaient dessins, sculptures et gravures. Transcription d\u2019une forme, d\u2019un motif \u00e0 un autre. De m\u00eame la peinture est transcription du plaisir d\u2019un moment de peinture. Il faut oublier le motif, le discours, la signification, coller son nez au tableau et suivre les mouvements de telle irisation qui cr\u00e9e le guet pour passer \u00e0 une autre couleur, et sauter de touches en touches de pinceau, et parcourir les lin\u00e9aments des craquelures\u2026 L\u2019\u0153il \u2013\u00a0\u00e7a n\u2019est plus le regard \u2013, l\u2019\u0153il sillonne le labyrinthe des plaisirs du peintre.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p1\">Yannick Vey propose au visiteur des labyrinthes d\u2019une autre structure. Leur parcours est simple, il s\u2019agit plut\u00f4t de chemins, d\u2019espaces born\u00e9s mais non enclos desquels il faut sortir ou bien l\u2019aventure est-elle int\u00e9rieure. Deux serpents en acier cir\u00e9 ench\u00e2ss\u00e9s indiquent au centre de l\u2019exposition un point d\u2019\u00e9nergies telluriques, qui, comme les reptiles, glissent et rampent dans le lieu. Mais ce sont les Minotaures invers\u00e9s quittant leur labyrinthe qui questionnent. De quelle copulation morganatique sont-ils les prog\u00e9nitures ? Dans cette toute r\u00e9cente s\u00e9rie de lithographies en deux couleurs, aux teintes d\u00e9licatement sombres, l\u2019artiste joue des possibilit\u00e9s sur le fil de l\u2019aquarelle en lithographie (ce qui est aussi, l\u2019un des grands jeux r\u00e9p\u00e9t\u00e9s de Deroubaix en litho) et avec la repr\u00e9sentation d\u2019un autoportrait polymorphe. Yannick Vey indique sans d\u00e9tour la source de sa pratique : acqu\u00e9rir un savoir-faire qui passe en premier lieu par l\u2019accueil de la col\u00e8re et de la haine constitutives de tout \u00eatre humain qui sont aussi un habit de la peur. Faire accueil, c\u2019est-\u00e0-dire nommer pour re-conna\u00eetre l<i>es pulsions d\u2019agressions et d\u2019autodestructions<\/i> singuli\u00e8res, n\u00e9anmoins commun\u00e9ment partag\u00e9es, dessine le chemin qui am\u00e8ne \u00e0 la sortie du labyrinthe pulsionnel. Civiliser les pulsions pourrait-on dire est un acte singulier et collectif, pas l\u2019un sans l\u2019autre. D\u00e8s lors les images, au-del\u00e0 de la m\u00e9taphore, visent un r\u00e9el.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\" wp-image-25988 aligncenter\" src=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-yannick-vey-villeurbanne-76-scaled.jpg\" alt=\"\" width=\"800\" height=\"1200\" srcset=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-yannick-vey-villeurbanne-76-scaled.jpg 1707w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-yannick-vey-villeurbanne-76-200x300.jpg 200w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-yannick-vey-villeurbanne-76-683x1024.jpg 683w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-yannick-vey-villeurbanne-76-768x1152.jpg 768w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-yannick-vey-villeurbanne-76-1024x1536.jpg 1024w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-yannick-vey-villeurbanne-76-1365x2048.jpg 1365w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-yannick-vey-villeurbanne-76-1333x2000.jpg 1333w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-yannick-vey-villeurbanne-76-1568x2352.jpg 1568w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p class=\"p1\">Revenons un instant sur le fil de l\u2019aquarelle lithographique : le principe physico-chimique joue de la relation antagoniste de l\u2019eau et de la graisse. L\u2019encre d\u2019imprimerie (grasse) adh\u00e8re au dessin (gras) de l\u2019artiste r\u00e9alis\u00e9 sur le calcaire. La goutte d\u2019huile ne se m\u00e9lange jamais \u00e0 l\u2019eau du verre secou\u00e9. Ainsi s\u2019effectue le transport du motif de la pierre humidifi\u00e9e au papier. <i>Transport<\/i>, Francis Ponge a parl\u00e9 de l\u2019amour, du baiser de la pierre. La sensualit\u00e9 \u00e9rotique du corps n\u2019est jamais \u00e9trang\u00e8re \u00e0 l\u2019artisanat. Une lithographie aquarell\u00e9e ajoute de l\u2019eau \u00e0 la graisse de l\u2019encre \u00e0 dessiner. D\u00e8s lors la polymorphie physique et chimique du dessin d\u00e9s\u00e9quilibre le processus technique. Pour l\u2019imprimeur c\u2019est une gageure. Pour l\u2019artiste il s\u2019agit de faire accueil \u00e0 l\u2019al\u00e9a, \u00e0 l\u2019accident. Damien Deroubaix et Yannick Vey se rejoignent dans cet accueil pictural et cette polymorphie de fait et r\u00e9p\u00e9t\u00e9e.<\/p>\n<p class=\"p1\">Yannick Vey manifeste aussi sa sensibilit\u00e9 et son go\u00fbt pour la polymorphie de la langue, les \u0153uvres en donnent les images ; parfois les titres indiquent le chemin. Ainsi n\u2019oublie-t-il pas ce que fut la langue fran\u00e7aise d\u2019avant sa fixation par Port-Royal. Cette fixation bien post\u00e9rieure suit le mouvement engag\u00e9 par l\u2019invention de la perspective : soit un monde hi\u00e9rarchis\u00e9, qui m\u00e9nage une place \u00e0 Dieu d\u2019o\u00f9 s\u2019ordonne chaque \u00e9l\u00e9ment visible et invisible du monde. \u00c7a n\u2019est pas sans effet sur la place m\u00e9nag\u00e9e \u00e0 l\u2019artiste et \u00e0 la cr\u00e9ation. Ainsi n\u2019oublie-t-il pas \u00ab\u00a0Le Pr\u00eache aux oiseaux\u00a0\u00bb, ni la l\u00e9gende, ni la fresque de Giotto (1295-1299). Un exemple de cette langue des oiseaux qu\u2019on peut entendre extrait des Bigarrures du Seigneur des Accords (1621) parce qu\u2019il articule l\u2019usage po\u00e9tique de la langue, au corps et \u00e0 la cr\u00e9ation, \u00e0 l\u2019objet : \u00ab Un Florentin amoureux d\u2019une\u00a0Barbara, portoit sa barbe longue, qui signifioit\u00a0Barba, &amp; une demie grenouillle, s\u00e7avoir la teste &amp; les deux pieds de devant, pour dire que ce n\u2019estoit que la premiere syllabe de\u00a0Rana\u00a0: il eut plus gaign\u00e9 de porter sa barbe raze demy : car cela eust fait\u00a0barbara-za. \u00bb\u00a0Ainsi l\u2019\u00ab\u00a0\u00c9chelle de Jacob\u00a0\u00bb, r\u00e9alis\u00e9e pour l\u2019exposition. \u00c0 la mani\u00e8re d\u2019un Midrash la\u00efque et buissonnier, l\u2019\u00e9chelle m\u00eale le pr\u00e9nom du lithographe, le savoir-faire de la sculpture et les puissances du r\u00eave de Jacob-Isra\u00ebl qui renouvelle l\u2019Alliance soit un pacte qui civilise le monde : un espace de m\u00e9taphores et d\u2019inventions communes, partag\u00e9.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p1\">Le pacte est fragile, \u00e0 quels \u00e9tir\u00e9ments, \u00e0 quelles polymorphies, \u00e0 quelles tensions peut-il tenir ? Quel est le point qui l\u2019\u00e9croule ? L\u2019invention \u2013 la cr\u00e9ation \u2013 c\u2019est d\u2019en proposer le renouvellement.<span class=\"Apple-converted-space\">\u00a0 <\/span>Les artistes y contribuent. \u00ab\u00a0<a href=\"https:\/\/urdla.com\/accueil\/3620-el-angel-exterminador-.htmlhttps:\/\/urdla.com\/accueil\/3620-el-angel-exterminador-.html\" target=\"_blank\" rel=\"noopener\">El Angel Exterminador<\/a>\u00a0\u00bb de Damien Deroubaix cl\u00f4t l\u2019exposition, elle reprend le motif d\u2019un grand tableau encore \u00e0 l\u2019atelier peint pour le Mus\u00e9e Goya de Castres, il fera face dans l\u2019exposition qui ouvre en juillet \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/La_Junte_des_Philippines#\/media\/Fichier:La_Junta_de_Filipinas.jpg\" target=\"_blank\" rel=\"noopener\">\u00ab\u00a0La Junte des Philippines\u00a0\u00bb<\/a>, tr\u00e8s grande toile de l\u2019artiste espagnol, peinte vers 1815. (La mani\u00e8re dont Deroubaix envisage ce face \u00e0 face \u00e9voque l\u2019interpr\u00e9tation des <i>M\u00e9nines<\/i> par Daniel Arasse.) La citation, la reprise de motifs du tableau original, augment\u00e9es d\u2019une trouvaille picturale d\u2019une grande finesse qui accentue la mise en regard, qui ne sera pas ici d\u00e9voil\u00e9e sauf \u00e0 dire que la peinture c\u2019est la lumi\u00e8re, signent le style de Damien Deroubaix. La lithographie n\u2019est pas une reproduction du tableau, elle est la traduction graphique du dispositif plastique. Dans la peinture, les membres de la compagnie ont pris la forme de totems qui s\u2019\u00e9rigent dans la salle du mus\u00e9e. Ce sont des sculptures de Gaston Damag (<i>Family Tree<\/i>). La commande \u00e0 laquelle Goya a r\u00e9pondu est li\u00e9e au pouvoir de Ferdinand VII d\u2019Espagne revenu d\u2019exil. Le r\u00e8gne du monarque n\u00e9 dans la conspiration (retour du poulpe) s\u2019installe dans l\u2019absolutisme et le conservatisme, \u00e0 l\u2019encontre des id\u00e9es des Lumi\u00e8res qui animaient le peintre. Entre 1810 et 1815, soit aux alentours de la r\u00e9alisation de cette toile (3205 x 4335 cm) Goya travaille \u00e0 la s\u00e9rie des quatre-vingt-deux gravures \u00ab\u00a0Les D\u00e9sastres de la guerre.\u00a0\u00bb Ainsi sommes-nous parvenus au croisement du pouvoir qu\u2019il soit r\u00e9galien ou bien celui du capitalisme (industriel naissant pour les membres de la junte ou financier mondialis\u00e9 comme il l\u2019est aujourd\u2019hui) et de la cr\u00e9ation d\u2019<i>un<\/i> artiste, soit la manifestation d\u2019un d\u00e9sir singulier qui m\u00e9conna\u00eet la norme et la morale, qui dessine un passage.<\/p>\n<p><img loading=\"lazy\" class=\" wp-image-25989 aligncenter\" src=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-b-villeurbanne-2-scaled.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-b-villeurbanne-2-scaled.jpg 2560w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-b-villeurbanne-2-300x200.jpg 300w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-b-villeurbanne-2-1024x683.jpg 1024w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-b-villeurbanne-2-768x512.jpg 768w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-b-villeurbanne-2-1536x1024.jpg 1536w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-b-villeurbanne-2-2048x1365.jpg 2048w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-b-villeurbanne-2-2000x1333.jpg 2000w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-b-villeurbanne-2-1568x1045.jpg 1568w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2024\/05\/cecile-cayon-urdla-damien-deroubaix-b-villeurbanne-2-272x182.jpg 272w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p class=\"p1\">C\u2019\u00e9tait il y a quinze ans. Le motif reproduit pour annoncer l\u2019exposition de Deroubaix \u00e0 URDLA \u00e9tait emprunt\u00e9 \u00e0 la grande gravure sur bois \u00ab\u00a0<a href=\"https:\/\/urdla.com\/catalogue\/342-un-homme-nouveau.html\" target=\"_blank\" rel=\"noopener\">Un homme nouveau<\/a>\u00a0\u00bb, le titre \u00e9voque la sculpture d\u2019Otto Freundlich qui fit la couverture du catalogue de l\u2019exposition <i>Art d\u00e9g\u00e9n\u00e9r\u00e9 <\/i>organis\u00e9e \u00e0 partir de 1937. Pour la gravure : un squelette de gorille d\u00e9f\u00e8que une bulle dans laquelle est \u00e9crit \u00ab\u00a0Money.\u00a0\u00bb L\u2019\u00e9grenage des dates depuis D\u00fcrer en passant par Jacques Callot et Goya, mais tout \u00e9tait d\u00e9j\u00e0 en place dans les grains de raisins de Zeuxis, jusqu\u2019\u00e0 Damien Deroubaix et Yannick Vey ne fait valoir que la r\u00e9p\u00e9tition des heurts sur les m\u00eames but\u00e9es de la censure et de la <i>sensure. <\/i>Leurs hoplites oublient que<i> \u00ab\u00a0toute l&rsquo;eau de la mer ne suffirait pas \u00e0 laver une t\u00e2che de sang intellectuelle.\u00a0\u00bb <\/i>(Lautr\u00e9mont). La fr\u00e9quentation des \u0153uvres et des artistes tient \u00e9veill\u00e9 dans la danse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Polymorphie est d\u00e8s lors d\u2019\u00e9vidence ; elle se feuillette dans la pratique (les media), dans les images (c\u2019est la mani\u00e8re m\u00eame de toute repr\u00e9sentation) et dans l\u2019amiti\u00e9 (elle en est le fondement).<\/p>\n","protected":false},"author":4,"featured_media":26028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[12,13],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/25974"}],"collection":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/comments?post=25974"}],"version-history":[{"count":10,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/25974\/revisions"}],"predecessor-version":[{"id":52570,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/25974\/revisions\/52570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/media\/26028"}],"wp:attachment":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/media?parent=25974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/categories?post=25974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/tags?post=25974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}