{"id":2148,"date":"2014-06-07T20:21:02","date_gmt":"2014-06-07T18:21:02","guid":{"rendered":"https:\/\/urdla.com\/blog\/?p=2148"},"modified":"2020-04-01T12:09:33","modified_gmt":"2020-04-01T10:09:33","slug":"assemblages-daniel-aulagnier-frederic-cordier","status":"publish","type":"post","link":"https:\/\/urdla.com\/blog\/assemblages-daniel-aulagnier-frederic-cordier\/","title":{"rendered":"<i>Assemblages<\/i>, <\/br>Daniel Aulagnier &#038; Fr\u00e9d\u00e9ric Cordier"},"content":{"rendered":"<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Dans une exposition-installation, Fr\u00e9d\u00e9ric Cordier (n\u00e9 en 1985 au Canada) et Daniel Aulagnier (n\u00e9 en 1943 \u00e0 Firminy) interrogeront les points de connivence et les \u00e9carts de leur pratique.<\/p>\n<p>L\u2019un (Fr\u00e9d\u00e9ric Cordier) propose de grandes linogravures: architectures industrielles et imaginaires.<br \/>\nJeune artiste dipl\u00f4m\u00e9 de l\u2019ECAL, il d\u00e9veloppe un travail de peinture sur plaques perfor\u00e9es, de dessins et de papiers peints s\u00e9rigraphi\u00e9s autour de la notion de grille. Ses motifs sont issus de logos, art g\u00e9om\u00e9trique, art islamique ou cannage. Il tapisse lui-m\u00eame chaque mur pour en faire une \u0153uvre unique.<\/p>\n<p>L\u2019autre (Daniel Aulagnier) dessine des outils imaginaires.<br \/>\nDe l\u2019intention \u00e0 la formulation : c\u2019est parce que [son] int\u00e9r\u00eat pour les signes antagonistes est toujours nourri d\u2019une multitude d\u2019exploitations physiques et d\u2019approches m\u00e9taphoriques [qu\u2019il] \u00e9volue r\u00e9guli\u00e8rement entre le monde de la technique et celui de l\u2019art [qu\u2019il a] recours \u00e0 diff\u00e9rentes formes d\u2019expression graphique.<\/p>\n<p>C\u2019est parce que l\u2019un et l\u2019autre parent de suffisamment d\u2019effets de r\u00e9el leurs pi\u00e8ces que le spectateur est dupe.<\/p>\n<\/div>\n<p><img loading=\"lazy\" class=\"size-full wp-image-2213 alignnone\" src=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2014\/06\/GIF_MUR.gif\" alt=\"\" width=\"741\" height=\"600\" \/><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dans une exposition-installation, Fr\u00e9d\u00e9ric Cordier (n\u00e9 en 1985 au Canada) et Daniel Aulagnier (n\u00e9 en 1943 \u00e0 Firminy) interrogeront les points de connivence et les \u00e9carts de leur pratique.<\/p>\n","protected":false},"author":4,"featured_media":2201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/2148"}],"collection":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/comments?post=2148"}],"version-history":[{"count":8,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/2148\/revisions"}],"predecessor-version":[{"id":2212,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/2148\/revisions\/2212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/media\/2201"}],"wp:attachment":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/media?parent=2148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/categories?post=2148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/tags?post=2148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}