{"id":169574,"date":"2026-03-24T14:24:08","date_gmt":"2026-03-24T13:24:08","guid":{"rendered":"https:\/\/urdla.com\/blog\/?p=169574"},"modified":"2026-03-25T15:35:48","modified_gmt":"2026-03-25T14:35:48","slug":"fixer-limage-en-mouvement","status":"publish","type":"post","link":"https:\/\/urdla.com\/blog\/fixer-limage-en-mouvement\/","title":{"rendered":"Fixer l\u2019image en mouvement"},"content":{"rendered":"<h2 class=\"p1\"><em><strong>Fixer l&rsquo;image en mouvement<\/strong><\/em><br \/>\n<span class=\"\"><b class=\"\">par les \u00e9tudiants de troisi\u00e8me ann\u00e9e option Art, de l\u2019ESADSE\u00a0<br class=\"\" \/>sous la direction artistique et la coordination de Fabrice Lauterjung<br \/>\n<\/b><\/span><\/h2>\n<h3>Pr\u00e9sentation avec les \u00e9l\u00e8ves le jeudi 2 avril, \u00e0 l\u2019occasion du jury, de 16 heures \u00e0 18 heures.<br \/>\n<br class=\"\" data-start=\"957\" data-end=\"960\" \/>Accrochage visible jusqu\u2019au vendredi 3 avril, de 10 heures \u00e0 18 heures.<\/h3>\n<div>\n<p>En soutien aux \u00e9coles d\u2019art et dans la volont\u00e9 d\u2019accompagner la professionnalisation des \u00e9tudiants, URDLA accueillera, les jeudi 2 et vendredi 3 avril 2026, les \u00e9tudiants de troisi\u00e8me ann\u00e9e participant au projet \u00ab Fixer l\u2019image en mouvement \u00bb, conduit par Fabrice Lauterjung, artiste et enseignant \u00e0 l\u2019ESADSE\u00a0.<\/p>\n<p>Ce projet, men\u00e9 dans un premier temps au sein de l\u2019\u00e9cole, donnera lieu \u00e0 une restitution publique \u00e0 URDLA, o\u00f9 seront pr\u00e9sent\u00e9s les travaux et recherches r\u00e9alis\u00e9s par les \u00e9tudiants. \u00c0 partir de cette pr\u00e9sentation, un jury compos\u00e9 de L\u00e9o Marin, directeur d\u2019URDLA, de Camille Paulhan, critique et enseignante \u00e0 l\u2019ENSBAL, et de Fabrice Lauterjung s\u00e9lectionnera un laur\u00e9at invit\u00e9 \u00e0 exp\u00e9rimenter l\u2019image imprim\u00e9e \u00e0 URDLA, avec l\u2019accompagnement de la direction artistique, en vue de l\u2019\u00e9dition d\u2019une estampe originale.<\/p>\n<p>Pr\u00e9sentation avec les \u00e9l\u00e8ves le jeudi 2 avril, \u00e0 l\u2019occasion du jury, de 16 heures \u00e0 18 heures.<br \/>\nAccrochage visible jusqu\u2019au vendredi 3 avril, de 10 heures \u00e0 18 heures.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fixer l&rsquo;image en mouvement par les \u00e9tudiants de troisi\u00e8me ann\u00e9e, option Art de l\u2019ESADSE<\/p>\n","protected":false},"author":4,"featured_media":169575,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/169574"}],"collection":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/comments?post=169574"}],"version-history":[{"count":17,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/169574\/revisions"}],"predecessor-version":[{"id":169632,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/169574\/revisions\/169632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/media\/169575"}],"wp:attachment":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/media?parent=169574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/categories?post=169574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/tags?post=169574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}