{"id":14953,"date":"2023-04-04T13:54:52","date_gmt":"2023-04-04T11:54:52","guid":{"rendered":"https:\/\/urdla.com\/blog\/?p=14953"},"modified":"2023-09-06T10:23:56","modified_gmt":"2023-09-06T08:23:56","slug":"dire-faire-exposition","status":"publish","type":"post","link":"https:\/\/urdla.com\/blog\/dire-faire-exposition\/","title":{"rendered":"DIRE &#038; FAIRE &#8211; exposition"},"content":{"rendered":"<h3><strong>DIRE &amp; FAIRE, Fabien Steichen, \u00e0 URDLA<\/strong><\/h3>\n<p class=\"p1\">Ce printemps, le catalogue URDLA s\u2019enrichit de 10 nouvelles \u00e9ditions, issues de la session 2021-2022 de <strong>DIRE &amp; FAIRE<\/strong>. 10 dates, 10 t\u00e9moins, 70 participants\u2026 ont abouti \u00e0 la cr\u00e9ation de 10 scenarii qui sont 10 nouvelles estampes r\u00e9unissant lithographie, texte en typographie et clich\u00e9s photographiques, fruits d\u2019une collaboration entre Fabien Steichen et Yan Charpentier. Elles donnent lieu \u00e0 la prochaine exposition \u00e0 URDLA dont l\u2019ouverture sera le samedi 13 mai, \u00e0 l\u2019occasion du <strong>Mai d\u2019Ad\u00e8le<\/strong>. Chaque participant se verra remettre l\u2019exemplaire de l\u2019\u00e9dition du sc\u00e9nario auquel il a contribu\u00e9.<\/p>\n<p style=\"text-align: left;\"><em>S\u2019installer seul sur un banc, attendre que quelqu\u2019un vienne s\u2019asseoir. Lui tendre un papier sur lequel est \u00e9crit : \u00ab \u2013 Vous avez vu ? \u00bb, suivre son intuition.<br \/>\n<\/em>sc\u00e9nario <strong>DIRE &amp; FAIRE<\/strong>\u00a0du 2 juillet 2021<\/p>\n<p style=\"text-align: left;\">15 participants.<br \/>\nUn invit\u00e9 anonyme livre le t\u00e9moignage d\u2019une exp\u00e9rience.<br \/>\nApr\u00e8s son d\u00e9part, accompagn\u00e9s par Fabien Steichen, les 15 participants \u00e9crivent ensemble le sc\u00e9nario d\u2019une performance activable par chacun \u00e0 son gr\u00e9, \u00e0 n\u2019importe quel moment.<br \/>\nLa vis\u00e9e : permettre des interactions sociales in\u00e9dites.<br \/>\nAu milieu de la soir\u00e9e un repas offert est pris en commun.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-14960\" src=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_0729-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_0729-scaled.jpg 2560w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_0729-300x200.jpg 300w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_0729-1024x683.jpg 1024w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_0729-768x512.jpg 768w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_0729-1536x1024.jpg 1536w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_0729-2048x1365.jpg 2048w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_0729-2000x1333.jpg 2000w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_0729-1568x1045.jpg 1568w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_0729-272x182.jpg 272w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>D\u00e9but\u00e9 en 2015 lors de Biennale d\u2019Art Contemporain de Lyon,\u00a0<strong>DIRE &amp; FAIRE<\/strong>\u00a0a pour objet l\u2019\u00e9laboration d\u2019une parole collective. \u00c0 l\u2019occasion de\u00a0<em>Villeurbanne 2022, Capitale fran\u00e7aise de la culture\u00a0<\/em>et de\u00a0<em>la Fabrique du nous #1<\/em>, projet collaboratif entre URDLA, l\u2019Institut d\u2019art contemporain et leurs partenaires, Fabien Steichen et URDLA ont pr\u00e9sent\u00e9\u00a0<strong>DIRE &amp; FAIRE<\/strong>\u00a0tout au long de la saison 2021-2022.\u00a0<em>La Fabrique du nous<\/em>, manifestation biennale, a pour objectif de cr\u00e9er du lien, de la rencontre, du partage avec les artistes et la puissance sensible de leurs imaginaires, en s\u2019adressant notamment aux habitants et aux habitantes, \u00e0 travers des moments d\u2019\u00e9changes et de partage pour (re)construire ce\u00a0<em>nous<\/em>.\u00a0<strong>DIRE &amp; FAIRE<\/strong>\u00a0a \u00e9t\u00e9 parall\u00e8lement un des 700 \u00e9v\u00e9nements labellis\u00e9s\u00a0<strong><em>Villeurbanne 2022, capitale fran\u00e7aise de la culture<\/em><\/strong><em>.<\/em><\/p>\n<p>Fabien Steichen met en sc\u00e8ne un espace public constitu\u00e9 de gestes d\u2019humanit\u00e9. Ainsi, il cr\u00e9e de discr\u00e8tes actions et t\u00e9moignages, susceptibles de cr\u00e9er des situations d\u00e9concertantes. En 2009, il offre des cubes de bronze aux passants, une exp\u00e9rience qui lui permet de cr\u00e9er d\u2019improbables rencontres et de g\u00e9n\u00e9rer de la s\u00e9rendipit\u00e9. Fabien Steichen est \u00e9galement l\u2019auteur de textes publi\u00e9s dans les revues\u00a0<em>Multitudes<\/em>,\u00a0<em>Nioques<\/em>\u00a0et\u00a0<em>Initiales<\/em>, et interpr\u00e9t\u00e9s au Palais de Tokyo, aux Laboratoires d\u2019Aubervilliers et \u00e0 la Maison de la po\u00e9sie de Paris.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-14961\" src=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_6083-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_6083-scaled.jpg 2560w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_6083-300x225.jpg 300w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_6083-1024x768.jpg 1024w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_6083-768x576.jpg 768w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_6083-1536x1152.jpg 1536w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_6083-2048x1536.jpg 2048w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_6083-2000x1500.jpg 2000w, https:\/\/urdla.com\/blog\/wp-content\/uploads\/2023\/03\/IMG_6083-1568x1176.jpg 1568w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p><strong>DIRE &amp; FAIRE<\/strong>\u00a0est un projet qui existe depuis septembre 2015 et r\u00e9unit \u00e0 chaque s\u00e9ance\u00a0 depuis cette date de nouveaux participants. Il s\u2019est d\u00e9roul\u00e9 au Nouveau Th\u00e9\u00e2tre du 8<sup>e\u00a0<\/sup>arrondissement de Lyon, \u00e0 l\u2019espace Pandora, dans les espaces d\u2019exposition \u201cchez N\u00e9on\u201d, \u00ab Attrape-Couleurs \u00bb, \u00e0 la \u00ab Galerie des Projets \u00bb, et dans le centre de culture urbaine \u00ab Archipel \u00bb .<\/p>\n<p>L\u2019exposition, depuis Marcel Duchamp, est une forme de mise en sc\u00e8ne qui articule le visible et l\u2019invisible. Au sein du monde contemporain, il est fr\u00e9quent d\u2019observer une \u00e9conomie sensible favoriser une confusion entre domaines public et priv\u00e9. Au contraire, l\u2019\u00e9conomie sensible de\u00a0<strong>DIRE &amp; FAIRE\u00a0<\/strong>s\u00e9pare le public du priv\u00e9 et g\u00e9n\u00e8re des dons de paroles \u2014 impossibles \u00e0 mesurer \u2014 de fa\u00e7on \u00e0 \u00e9largir l\u2019attention des participants qui concourent \u00e0 faire exister cette institution sociale.<\/p>\n<p>Ainsi, lorsque les participants cr\u00e9ent un sc\u00e9nario, ils constituent une assembl\u00e9e priv\u00e9e puisqu\u2019aucun enregistrement permettant de d\u00e9voiler le processus de r\u00e9alisation n\u2019est tol\u00e9r\u00e9. Seul le sc\u00e9nario est publi\u00e9. De m\u00eame, ni document, ni tierce personne ne peuvent attester l\u2019interpr\u00e9tation des sc\u00e9narios, ex\u00e9cut\u00e9s obligatoirement en face-\u00e0-face.<\/p>\n<p>Ce dispositif conduit dans l\u2019espace public tangible des interpr\u00e8tes qui, gr\u00e2ce aux sc\u00e9narios, peuvent se mettre en situation de repr\u00e9sentation sans craindre la publicit\u00e9 de leurs actes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce printemps, le catalogue URDLA s\u2019enrichit de 10 nouvelles \u00e9ditions, issues de la session 2021-2022 de\u00a0DIRE &#038; FAIRE. 10 dates, 10 t\u00e9moins, 70 participants\u2026<\/p>\n","protected":false},"author":4,"featured_media":14954,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/14953"}],"collection":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/comments?post=14953"}],"version-history":[{"count":33,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/14953\/revisions"}],"predecessor-version":[{"id":16099,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/posts\/14953\/revisions\/16099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/media\/14954"}],"wp:attachment":[{"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/media?parent=14953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/categories?post=14953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urdla.com\/blog\/wp-json\/wp\/v2\/tags?post=14953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}